{"id":3290,"date":"2019-08-26T14:44:14","date_gmt":"2019-08-26T12:44:14","guid":{"rendered":"https:\/\/www.kraeuterhaus.de\/blog\/?p=3290"},"modified":"2025-06-18T09:20:53","modified_gmt":"2025-06-18T07:20:53","slug":"gesunde-reiseorte","status":"publish","type":"post","link":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/","title":{"rendered":"Gesunde Reiseorte f\u00fcr Ihren Urlaub"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span><article class=\"entry-content\"><p>Auf in die weite Welt \u2013 alles entdecken, sehen, erleben! Reisen ist sicherlich eines der sch\u00f6nsten Dinge im Leben. Wie sagte der Theologe Aurelius Augustinus doch einst? \u201eDie Welt ist ein Buch. Wer nie reist, sieht nur eine Seite davon.\u201c \u2013 \u00a0Recht hatte er. Doch denken Sie, wenn Sie Ihren Urlaub planen, auch an Ihre Gesundheit. Denn manchmal liegt das Ferne doch so nah. Deutschland hat so viel zu bieten und warum nicht einmal die deutschen Kurorte besuchen und zwei Fliegen mit einer Klappe schlagen?<\/p>\n<h2><strong>Die heilenden Kr\u00e4fte der Kurorte <\/strong><\/h2>\n<p>\u201eKurorte!\u201c Das Wort geht einem so leicht \u00fcber die Lippen, aber was genau versteht man \u00fcberhaupt darunter? \u201eKurorte sind Gemeinden oder Teile von Gemeinden, in denen nat\u00fcrliche Heilmittel des Bodens oder des Klimas oder [\u2026] Heilverfahren [\u2026] zur Vorbeugung gegen Krankheiten oder zu deren Heilung oder Linderung durch zweckentsprechende Einrichtungen angewendet werden und die einen entsprechenden Ortscharakter aufweisen,\u201c hei\u00dft es in der Definition des Kurortegesetzes. (\u00a71 Art. 1 KOG)<\/p>\n<p>Die Gesundheit aller Besucher steht jederzeit an oberster Stelle. Damit sich ein Ort den Titel zu eigen machen kann, m\u00fcssen Qualit\u00e4tsstandards eingehalten werden. Alle Anforderungen aus dem deutschen Kurortegesetz m\u00fcssen erf\u00fcllt sein. Erst dann kann eine Ernennung zum Kurort erfolgen. In diesem Fall darf der Ort Kurtaxe erheben, um die Besonderheiten des Ortes weiter erhalten zu k\u00f6nnen.<\/p>\n<p>Diese gesunden Reiseorte zeichnen sich vor allem durch folgende Eigenschaften aus:<\/p>\n<ul>\n<li>Diverse Kurheilverfahren,<\/li>\n<li>Wellnessbehandlungen,<\/li>\n<li>Spezialisten, z. B. speziell ausgebildete \u00c4rzte,<\/li>\n<li>reizvolle Landschaften und frische Luft,<\/li>\n<li>ausgewogene Freizeitaktivit\u00e4ten von Entspannung bis zum Auspowern,<\/li>\n<li>Kunst &amp; Kultur sowie<\/li>\n<li>kulinarische Gen\u00fcsse.<\/li>\n<\/ul>\n<h2><strong>Die sch\u00f6nsten Kurorte in Deutschland<\/strong><\/h2>\n<p>Ihr Koffer steht fast schon gepackt in der Ecke. Jetzt hei\u00dft es nur noch, ein Reiseziel f\u00fcr den Urlaub ausw\u00e4hlen und los geht es. Sie m\u00f6chten all die Annehmlichkeiten eines Kurortes in Anspruch nehmen, wissen aber nicht, wo es hingehen soll? Wir haben hier unsere Top 10 Reiseziele f\u00fcr Sie als Tipps zusammengefasst:<\/p>\n<ul>\n<li>Bad W\u00f6rishofen: Hier befindet sich das Zentrum der Kneipp-Kur, denn Mitte des 19. Jahrhunderts kam der Geistliche Sebastian Kneipp in das bayrische Land und linderte mit Wasser Leiden.<\/li>\n<li>Bad Oeynhausen: Erleben Sie neben Wellness pur pr\u00e4chtige Gr\u00fcnderzeitarchitektur mitten in Nordrhein-Westfalen.<\/li>\n<li>Norderney: Reine Nordseeluft schnuppern und als Kurgast alle Vorz\u00fcge der deutschen Nordseeinsel genie\u00dfen \u2013 wo kann man das besser als an einem 14 km langen Sandstrand?<\/li>\n<li>Heiligendamm: Das Ostseebad ist der \u00e4lteste Seebadeort Deutschlands und wird, aufgrund der nach englischem Vorbild gebauten wei\u00dfen Badeh\u00e4user, auch die \u201ewei\u00dfe Stadt am Meer\u201c genannt. Kein Wunder, dass sich der Adel es sich hier gerne gutgehen lassen hat.<\/li>\n<li>Bad Wildungen: Hessen hat sich gemacht! Einst kamen gerade einmal 15 Kurg\u00e4ste in den Badeort, heute geh\u00f6rt der Kurort zu den gr\u00f6\u00dften Kurzentren des Landes.<\/li>\n<li>Bad T\u00f6lz: Sp\u00e4testens seit der gleichnamigen Fernsehserie ist Bad T\u00f6lz \u00fcber die Grenzen des Landes bekannt. Die Tradition des Kurorts reicht bereits mehr als 150 Jahre zur\u00fcck.<\/li>\n<li>Bad Pyrmont: Zwischen Weserbergland und Teutoburger Wald versteckt sich dieser Hotspot des Adels. Geschichtlich hat der Ort einiges zu bieten und sind Sie erst im Kurpark, kommen Sie sicher aus dem Staunen nicht mehr heraus. Der Park wurde nicht umsonst 2006 als einer der sch\u00f6nsten Parks Europas ausgezeichnet.<\/li>\n<li>Bad Saarow: Wenn Sie an mineralreichen Schlamm denken, sollten Sie an Bad Saarow denken, denn daf\u00fcr ist der Erholungsort bekannt. Und dieser wurde schon f\u00fcr die ein oder andere Hauterkrankung eingesetzt.<\/li>\n<li>Baden-Baden: Schon die R\u00f6mer f\u00fchlten sich hier pudelwohl. Badruinen aus der R\u00f6merzeit und ein malerischer Schlossgarten erwarten Sie in einem der bedeutendsten deutschen Thermalb\u00e4der.<\/li>\n<li>Bad Ditzenbach: Sicherlich nicht so ber\u00fchmt wie einige andere Kurorte, jedoch genauso erholsam und gesundheitsf\u00f6rdernd ist Bad Ditzenbach. Heilende Mineralquellen, gesunde Luft und die wundersch\u00f6ne Natur der schw\u00e4bischen Alb lassen ihr Herz h\u00f6her schlagen.<\/li>\n<\/ul>\n<p>Und wenn wir schon beim Thema sind: Genau hier, in Bad Ditzenbach, ist unser Kr\u00e4uterhaus Sanct Bernhard beheimatet. Mit unserer Produktion, dem <a href=\"https:\/\/www.kraeuterhaus.de\/ueber-uns\/de-DE\/ladengeschaefte?campaign=blog\/gesunde_reiseorte\/link&amp;utm_source=social&amp;utm_campaign=blog&amp;utm_medium=link&amp;utm_term=ladenlokal&amp;utm_content=gesunde_reiseorte\">Ladengesch\u00e4ft<\/a> und dem 3.000 m\u00b2 gro\u00dfen <a href=\"https:\/\/www.kraeuterhaus.de\/ueber-uns\/de-DE\/erlebnis-kraeutergarten?campaign=blog\/gesunde_reiseorte\/link&amp;utm_source=social&amp;utm_campaign=blog&amp;utm_medium=link&amp;utm_term=kraeutergarten&amp;utm_content=gesunde_reiseorte\">Kr\u00e4utergarten<\/a> freuen wir uns jederzeit \u00fcber Ihren Besuch. \u00dcbernachten k\u00f6nnen Sie im <a href=\"https:\/\/www.wellnesshotel-sanct-bernhard.de\/?campaign=blog\/gesunde_reiseorte\/link&amp;utm_source=social&amp;utm_campaign=blog&amp;utm_medium=link&amp;utm_term=vitalhotel&amp;utm_content=gesunde_reiseorte\">Wellnesshotel Sanct Bernhard<\/a> und sich dort auch mit der ein oder anderen Anwendung oder Kur entspannen. Nebenbei gibt es zu Fu\u00df oder mit dem Rad die wundersch\u00f6ne Umgebung zu entdecken.<\/p>\n<h2><strong>Unser Tipp:<\/strong><\/h2>\n<p>Besonders der schw\u00e4bische Indian Summer wird Sie begeistern! Wenn sich im Herbst die W\u00e4lder kunterbunt verf\u00e4rben, k\u00f6nnen Sie sich nicht mehr satt sehen. Ein farbenpr\u00e4chtiges Schauspiel leuchtet Ihnen entgegen und zaubert Ihnen beim Wandern oder einer Radtour unter Garantie ein L\u00e4cheln ins Gesicht und macht Ihren Urlaub zu einem unvergesslichen Ereignis.<\/p>\n<\/article>","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Lesezeit: <\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">Minuten<\/span><\/span>Auf in die weite Welt \u2013 alles entdecken, sehen, erleben! Reisen ist sicherlich eines der sch\u00f6nsten Dinge im Leben. Wie sagte der Theologe Aurelius&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3289,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[175,233,1352,1351,1350,1354,1345,1353],"class_list":["post-3290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesundheit","tag-entspannung","tag-gesundheit","tag-heilbad","tag-kurorte","tag-reiseorte","tag-reiseziele","tag-urlaub","tag-vitalhotel","post-item","post-even"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gesunde Reiseorte f\u00fcr Ihren Urlaub<\/title>\n<meta name=\"description\" content=\"Entdecken Sie die sch\u00f6nsten Kurorte von Deutschland. G\u00f6nnen Sie Ihrem K\u00f6rper Urlaub und tun Sie gleichzeitig Ihrer Gesundheit etwas Gutes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesunde Reiseorte f\u00fcr Ihren Urlaub\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie die sch\u00f6nsten Kurorte von Deutschland. G\u00f6nnen Sie Ihrem K\u00f6rper Urlaub und tun Sie gleichzeitig Ihrer Gesundheit etwas Gutes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/\" \/>\n<meta property=\"og:site_name\" content=\"Wertvolles Wissen f\u00fcr Ihre Gesundheit und Sch\u00f6nheit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Kraeuterhaus\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/Kraeuterhaus\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-26T12:44:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T07:20:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kraeuterhaus.de\/blog\/wp-content\/uploads\/2019\/07\/gesunde_reiseorte_1150x640.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1150\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kr\u00e4uterhaus Team\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kr\u00e4uterhaus Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/\"},\"author\":{\"name\":\"Kr\u00e4uterhaus Team\",\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/#\\\/schema\\\/person\\\/15829ed1eec9aa47cd7a137a021e7848\"},\"headline\":\"Gesunde Reiseorte f\u00fcr Ihren Urlaub\",\"datePublished\":\"2019-08-26T12:44:14+00:00\",\"dateModified\":\"2025-06-18T07:20:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/\"},\"wordCount\":776,\"publisher\":{\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/gesunde_reiseorte_1150x640.jpg\",\"keywords\":[\"entspannung\",\"Gesundheit\",\"Heilbad\",\"Kurorte\",\"Reiseorte\",\"Reiseziele\",\"Urlaub\",\"Vitalhotel\"],\"articleSection\":[\"Gesundheit\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/\",\"url\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/\",\"name\":\"Gesunde Reiseorte f\u00fcr Ihren Urlaub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/gesunde_reiseorte_1150x640.jpg\",\"datePublished\":\"2019-08-26T12:44:14+00:00\",\"dateModified\":\"2025-06-18T07:20:53+00:00\",\"description\":\"Entdecken Sie die sch\u00f6nsten Kurorte von Deutschland. G\u00f6nnen Sie Ihrem K\u00f6rper Urlaub und tun Sie gleichzeitig Ihrer Gesundheit etwas Gutes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/gesunde_reiseorte_1150x640.jpg\",\"contentUrl\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/gesunde_reiseorte_1150x640.jpg\",\"width\":1150,\"height\":640,\"caption\":\"Entdecken Sie gesunde Reiseorte in Ihrem Urlaub!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/gesunde-reiseorte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gesunde Reiseorte f\u00fcr Ihren Urlaub\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/\",\"name\":\"Wertvolles Wissen f\u00fcr Ihre Gesundheit und Sch\u00f6nheit\",\"description\":\"Willkommen auf unserem Weblog\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/#organization\",\"name\":\"Kr\u00e4uterhaus Sanct Bernhard\",\"url\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logo.gif\",\"contentUrl\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/logo.gif\",\"width\":213,\"height\":85,\"caption\":\"Kr\u00e4uterhaus Sanct Bernhard\"},\"image\":{\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Kraeuterhaus\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sanct.bernhard.official\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCtELoLvQTdj9iohrAryTGbA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/#\\\/schema\\\/person\\\/15829ed1eec9aa47cd7a137a021e7848\",\"name\":\"Kr\u00e4uterhaus Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c5e6ac23e90621494e8b98ac4e160109ffbe8675b46f4875cebfbbd2d54796c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c5e6ac23e90621494e8b98ac4e160109ffbe8675b46f4875cebfbbd2d54796c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0c5e6ac23e90621494e8b98ac4e160109ffbe8675b46f4875cebfbbd2d54796c?s=96&d=mm&r=g\",\"caption\":\"Kr\u00e4uterhaus Team\"},\"sameAs\":[\"https:\\\/\\\/www.kraeuterhaus.de\\\/\",\"https:\\\/\\\/www.facebook.com\\\/Kraeuterhaus\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sanct.bernhard.official\\\/\"],\"url\":\"https:\\\/\\\/www.kraeuterhaus.de\\\/blog\\\/unsere-autoren\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesunde Reiseorte f\u00fcr Ihren Urlaub","description":"Entdecken Sie die sch\u00f6nsten Kurorte von Deutschland. G\u00f6nnen Sie Ihrem K\u00f6rper Urlaub und tun Sie gleichzeitig Ihrer Gesundheit etwas Gutes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/","og_locale":"de_DE","og_type":"article","og_title":"Gesunde Reiseorte f\u00fcr Ihren Urlaub","og_description":"Entdecken Sie die sch\u00f6nsten Kurorte von Deutschland. G\u00f6nnen Sie Ihrem K\u00f6rper Urlaub und tun Sie gleichzeitig Ihrer Gesundheit etwas Gutes.","og_url":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/","og_site_name":"Wertvolles Wissen f\u00fcr Ihre Gesundheit und Sch\u00f6nheit","article_publisher":"https:\/\/www.facebook.com\/Kraeuterhaus\/","article_author":"https:\/\/www.facebook.com\/Kraeuterhaus\/","article_published_time":"2019-08-26T12:44:14+00:00","article_modified_time":"2025-06-18T07:20:53+00:00","og_image":[{"width":1150,"height":640,"url":"https:\/\/www.kraeuterhaus.de\/blog\/wp-content\/uploads\/2019\/07\/gesunde_reiseorte_1150x640.jpg","type":"image\/jpeg"}],"author":"Kr\u00e4uterhaus Team","twitter_misc":{"Verfasst von":"Kr\u00e4uterhaus Team","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/#article","isPartOf":{"@id":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/"},"author":{"name":"Kr\u00e4uterhaus Team","@id":"https:\/\/www.kraeuterhaus.de\/blog\/#\/schema\/person\/15829ed1eec9aa47cd7a137a021e7848"},"headline":"Gesunde Reiseorte f\u00fcr Ihren Urlaub","datePublished":"2019-08-26T12:44:14+00:00","dateModified":"2025-06-18T07:20:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/"},"wordCount":776,"publisher":{"@id":"https:\/\/www.kraeuterhaus.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kraeuterhaus.de\/blog\/wp-content\/uploads\/2019\/07\/gesunde_reiseorte_1150x640.jpg","keywords":["entspannung","Gesundheit","Heilbad","Kurorte","Reiseorte","Reiseziele","Urlaub","Vitalhotel"],"articleSection":["Gesundheit"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/","url":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/","name":"Gesunde Reiseorte f\u00fcr Ihren Urlaub","isPartOf":{"@id":"https:\/\/www.kraeuterhaus.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/#primaryimage"},"image":{"@id":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.kraeuterhaus.de\/blog\/wp-content\/uploads\/2019\/07\/gesunde_reiseorte_1150x640.jpg","datePublished":"2019-08-26T12:44:14+00:00","dateModified":"2025-06-18T07:20:53+00:00","description":"Entdecken Sie die sch\u00f6nsten Kurorte von Deutschland. G\u00f6nnen Sie Ihrem K\u00f6rper Urlaub und tun Sie gleichzeitig Ihrer Gesundheit etwas Gutes.","breadcrumb":{"@id":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/#primaryimage","url":"https:\/\/www.kraeuterhaus.de\/blog\/wp-content\/uploads\/2019\/07\/gesunde_reiseorte_1150x640.jpg","contentUrl":"https:\/\/www.kraeuterhaus.de\/blog\/wp-content\/uploads\/2019\/07\/gesunde_reiseorte_1150x640.jpg","width":1150,"height":640,"caption":"Entdecken Sie gesunde Reiseorte in Ihrem Urlaub!"},{"@type":"BreadcrumbList","@id":"https:\/\/www.kraeuterhaus.de\/blog\/gesunde-reiseorte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.kraeuterhaus.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Gesunde Reiseorte f\u00fcr Ihren Urlaub"}]},{"@type":"WebSite","@id":"https:\/\/www.kraeuterhaus.de\/blog\/#website","url":"https:\/\/www.kraeuterhaus.de\/blog\/","name":"Wertvolles Wissen f\u00fcr Ihre Gesundheit und Sch\u00f6nheit","description":"Willkommen auf unserem Weblog","publisher":{"@id":"https:\/\/www.kraeuterhaus.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kraeuterhaus.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.kraeuterhaus.de\/blog\/#organization","name":"Kr\u00e4uterhaus Sanct Bernhard","url":"https:\/\/www.kraeuterhaus.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.kraeuterhaus.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.kraeuterhaus.de\/blog\/wp-content\/uploads\/2016\/10\/logo.gif","contentUrl":"https:\/\/www.kraeuterhaus.de\/blog\/wp-content\/uploads\/2016\/10\/logo.gif","width":213,"height":85,"caption":"Kr\u00e4uterhaus Sanct Bernhard"},"image":{"@id":"https:\/\/www.kraeuterhaus.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Kraeuterhaus\/","https:\/\/www.instagram.com\/sanct.bernhard.official\/","https:\/\/www.youtube.com\/channel\/UCtELoLvQTdj9iohrAryTGbA"]},{"@type":"Person","@id":"https:\/\/www.kraeuterhaus.de\/blog\/#\/schema\/person\/15829ed1eec9aa47cd7a137a021e7848","name":"Kr\u00e4uterhaus Team","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/0c5e6ac23e90621494e8b98ac4e160109ffbe8675b46f4875cebfbbd2d54796c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0c5e6ac23e90621494e8b98ac4e160109ffbe8675b46f4875cebfbbd2d54796c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c5e6ac23e90621494e8b98ac4e160109ffbe8675b46f4875cebfbbd2d54796c?s=96&d=mm&r=g","caption":"Kr\u00e4uterhaus Team"},"sameAs":["https:\/\/www.kraeuterhaus.de\/","https:\/\/www.facebook.com\/Kraeuterhaus\/","https:\/\/www.instagram.com\/sanct.bernhard.official\/"],"url":"https:\/\/www.kraeuterhaus.de\/blog\/unsere-autoren\/"}]}},"views":10313,"_links":{"self":[{"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/posts\/3290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/comments?post=3290"}],"version-history":[{"count":5,"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/posts\/3290\/revisions"}],"predecessor-version":[{"id":4972,"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/posts\/3290\/revisions\/4972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/media\/3289"}],"wp:attachment":[{"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/media?parent=3290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/categories?post=3290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kraeuterhaus.de\/blog\/wp-json\/wp\/v2\/tags?post=3290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}